{"id":7,"date":"2025-04-23T09:34:33","date_gmt":"2025-04-23T09:34:33","guid":{"rendered":"https:\/\/joobond.com\/home\/"},"modified":"2025-06-25T16:28:29","modified_gmt":"2025-06-25T08:28:29","slug":"home","status":"publish","type":"page","link":"https:\/\/joobond.com\/es\/","title":{"rendered":"Quality Sealant Factory from China"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-7d5944be default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-a6e5678a\">\n<div class=\"wp-block-uagb-container uagb-block-72888ee5\">\n<figure data-spectra-id=\"spectra-11f6c18d-0def-40e4-b5bd-f84e51e42934\" class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"700\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner.webp\" alt=\"\" class=\"wp-image-2762\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner.webp 1920w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner-300x109.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner-1024x373.webp 1024w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner-768x280.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner-1536x560.webp 1536w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner-18x7.webp 18w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/banner-600x219.webp 600w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2169cbd9 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-356613ba\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e986d9d5\"><h1 class=\"uagb-heading-text\">Ayudamos a su empresa a crear v\u00ednculos m\u00e1s fuertes.<\/h1><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-34dff01e\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d9cb8524\"><p class=\"uagb-desc-text\"><em>Nuestras avanzadas soluciones adhesivas ayudan a las industrias a conseguir resultados duraderos y de alto rendimiento en automoci\u00f3n, construcci\u00f3n y fabricaci\u00f3n. Perm\u00edtanos fortalecer sus productos.<\/em><\/p><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a9633eaa alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-image uagb-block-44c89d1e wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/medium-banner-1.webp ,https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/medium-banner-1.webp 780w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/medium-banner-1-300x169.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/medium-banner-1.webp\" alt=\"\" class=\"uag-image-2164\" width=\"1140\" height=\"575\" title=\"mediano-banner\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-926b8013 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-bcbb6009\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1eef76a8\"><h6 class=\"uagb-heading-text\">Acerca de<\/h6><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-aa57526f\"><h2 class=\"uagb-heading-text\">Somos fabricantes certificados de adhesivos de alto rendimiento.<\/h2><p class=\"uagb-desc-text\">Joobond es un fabricante de sellantes especializado que se compromete a ofrecer soluciones de adhesi\u00f3n superiores para su industria.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-dab7cfbd wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory-1024x683.webp ,https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory-scaled.webp 780w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory-scaled.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory-1024x683.webp\" alt=\"\" class=\"uag-image-2173\" width=\"650\" height=\"450\" title=\"f\u00e1brica\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-05d59665\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-261d01ec wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Scenario-1-1024x731.webp ,https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Scenario-1.webp 780w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Scenario-1.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Scenario-1-1024x731.webp\" alt=\"\" class=\"uag-image-2175\" width=\"650\" height=\"450\" title=\"Escenario 1\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-0c48022c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Nuestra misi\u00f3n<\/h2><\/div><p class=\"uagb-ifb-desc\">Nos esforzamos por fortalecer sus productos desarrollando adhesivos innovadores que soportan tensiones y condiciones extremas. Nuestro equipo de qu\u00edmicos e ingenieros expertos crea soluciones fiables que unen su \u00e9xito, garantizando un rendimiento duradero.<\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-73d6529f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-4a7328e4\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-897ad235\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-93af6ed7 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Sellador de muros cortina<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M502.6 278.6l-128 128c-12.51 12.51-32.76 12.49-45.25 0c-12.5-12.5-12.5-32.75 0-45.25L402.8 288H32C14.31 288 0 273.7 0 255.1S14.31 224 32 224h370.8l-73.38-73.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l128 128C515.1 245.9 515.1 266.1 502.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2659f406\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-6e1a09f0\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-fd369e15 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Sellador de decoraci\u00f3n interior<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M502.6 278.6l-128 128c-12.51 12.51-32.76 12.49-45.25 0c-12.5-12.5-12.5-32.75 0-45.25L402.8 288H32C14.31 288 0 273.7 0 255.1S14.31 224 32 224h370.8l-73.38-73.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l128 128C515.1 245.9 515.1 266.1 502.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-06538a18\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-36618dbf\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-2b3de640 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Sellante para automoci\u00f3n<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M502.6 278.6l-128 128c-12.51 12.51-32.76 12.49-45.25 0c-12.5-12.5-12.5-32.75 0-45.25L402.8 288H32C14.31 288 0 273.7 0 255.1S14.31 224 32 224h370.8l-73.38-73.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l128 128C515.1 245.9 515.1 266.1 502.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ddbcb7a\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-7b9b18e7\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-a4ce54b0 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Sellador de puertas y ventanas<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M502.6 278.6l-128 128c-12.51 12.51-32.76 12.49-45.25 0c-12.5-12.5-12.5-32.75 0-45.25L402.8 288H32C14.31 288 0 273.7 0 255.1S14.31 224 32 224h370.8l-73.38-73.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l128 128C515.1 245.9 515.1 266.1 502.6 278.6z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e2755050 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-1c410426\">\n<div class=\"wp-block-uagb-image uagb-block-a3371d64 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/PU.webp ,https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/PU.webp 780w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/PU.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/PU.webp\" alt=\"\" class=\"uag-image-2170\" width=\"800\" height=\"534\" title=\"PU\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-80693cba\">\n<div class=\"wp-block-uagb-info-box uagb-block-84cb56a6 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><span class=\"uagb-ifb-title-prefix\">nueva colecci\u00f3n<\/span><h2 class=\"uagb-ifb-title\">Soluciones de sellado de PU de primera calidad<\/h2><\/div><p class=\"uagb-ifb-desc\">Selladores de poliuretano especializados para aplicaciones de montaje de autom\u00f3viles y construcci\u00f3n. Dise\u00f1ados para ofrecer una resistencia superior a la intemperie, durabilidad y una adherencia duradera.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/joobond.com\/es\/productos\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">Explorar todos los productos<\/span><\/a><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-267e3d1f\"><div class=\"woocommerce columns-3\"><ul class=\"products columns-3\">\n<li class=\"desktop-align-center tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-gallery-with-no-image ast-product-tabs-layout-horizontal product type-product post-2350 status-publish first instock product_cat-polyurethane-sealant product_cat-construction-sealant product_tag-construction-sealant has-post-thumbnail shipping-taxable product-type-simple\">\n\t<a href=\"https:\/\/joobond.com\/es\/producto\/j-340a-sellador-para-la-construccion\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340A-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"J-340A Sellador para la construcci\u00f3n\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340A-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340A-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340A-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340A-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340A-100x100.webp 100w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340A.webp 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">J-340A Sellador para la construcci\u00f3n<\/h2>\n<\/a><a href=\"https:\/\/joobond.com\/es\/producto\/j-340a-sellador-para-la-construccion\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2350\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"2350\" data-product_sku=\"\" aria-label=\"M\u00e1s informaci\u00f3n sobre &quot;J-340A Construction Sealant\" rel=\"nofollow\" data-success_message=\"\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Seguir leyendo<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2350\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"desktop-align-center tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-gallery-with-no-image ast-product-tabs-layout-horizontal product type-product post-2351 status-publish instock product_cat-polyurethane-sealant product_cat-construction-sealant product_tag-construction-sealant has-post-thumbnail shipping-taxable product-type-simple\">\n\t<a href=\"https:\/\/joobond.com\/es\/producto\/j-340b-sellador-para-la-construccion\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340B-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"J-340B Sellador para la construcci\u00f3n\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340B-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340B-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340B-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340B-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340B-100x100.webp 100w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-340B.webp 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">J-340B Sellador para la construcci\u00f3n<\/h2>\n<\/a><a href=\"https:\/\/joobond.com\/es\/producto\/j-340b-sellador-para-la-construccion\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2351\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"2351\" data-product_sku=\"\" aria-label=\"M\u00e1s informaci\u00f3n sobre &quot;J-340B Construction Sealant\" rel=\"nofollow\" data-success_message=\"\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Seguir leyendo<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2351\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"desktop-align-center tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-gallery-with-no-image ast-product-tabs-layout-horizontal product type-product post-2665 status-publish last instock product_cat-polyurethane-sealant product_cat-construction-sealant product_tag-construction-sealant has-post-thumbnail shipping-taxable product-type-simple\">\n\t<a href=\"https:\/\/joobond.com\/es\/producto\/sellante-de-construccion-j-340h\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-340H-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"J-340H Sellador para la construcci\u00f3n\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-340H-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-340H-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-340H-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-340H-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-340H-100x100.webp 100w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-340H.webp 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">J-340H Sellador para la construcci\u00f3n<\/h2>\n<\/a><a href=\"https:\/\/joobond.com\/es\/producto\/sellante-de-construccion-j-340h\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2665\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"2665\" data-product_sku=\"\" aria-label=\"M\u00e1s informaci\u00f3n sobre &quot;J-340H Construction Sealant\" rel=\"nofollow\" data-success_message=\"\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Seguir leyendo<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2665\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"desktop-align-center tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-gallery-with-no-image ast-product-tabs-layout-horizontal product type-product post-2319 status-publish first instock product_cat-polyurethane-sealant product_cat-windshield-adhesive product_tag-automotive-sealant has-post-thumbnail shipping-taxable product-type-simple\">\n\t<a href=\"https:\/\/joobond.com\/es\/producto\/adhesivo-de-poliuretano-para-parabrisas\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-518-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"J-518 Adhesivo de poliuretano para parabrisas de autom\u00f3viles\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-518-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-518-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-518-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-518-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-518-100x100.webp 100w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-518.webp 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">J-518 Adhesivo de poliuretano para parabrisas de autom\u00f3viles<\/h2>\n<\/a><a href=\"https:\/\/joobond.com\/es\/producto\/adhesivo-de-poliuretano-para-parabrisas\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2319\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"2319\" data-product_sku=\"\" aria-label=\"M\u00e1s informaci\u00f3n sobre &quot;J-518 Polyurethane Automotive Windshield Adhesive\" rel=\"nofollow\" data-success_message=\"\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Seguir leyendo<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2319\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"desktop-align-center tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-gallery-with-no-image ast-product-tabs-layout-horizontal product type-product post-2662 status-publish instock product_cat-polyurethane-sealant product_cat-windshield-adhesive product_tag-automotive-sealant has-post-thumbnail shipping-taxable product-type-simple\">\n\t<a href=\"https:\/\/joobond.com\/es\/producto\/j-518l-adhesivo-de-poliuretano-para-parabrisas-de-automocion\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"J-518L Adhesivo de poliuretano para parabrisas de autom\u00f3viles\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-100x100.webp 100w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L.webp 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">J-518L Adhesivo de poliuretano para parabrisas de autom\u00f3viles<\/h2>\n<\/a><a href=\"https:\/\/joobond.com\/es\/producto\/j-518l-adhesivo-de-poliuretano-para-parabrisas-de-automocion\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2662\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"2662\" data-product_sku=\"\" aria-label=\"M\u00e1s informaci\u00f3n sobre &quot;J-518L Polyurethane Automotive Windshield Adhesive\" rel=\"nofollow\" data-success_message=\"\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Seguir leyendo<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2662\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"desktop-align-center tablet-align-left mobile-align-left ast-product-gallery-layout-horizontal-slider ast-product-gallery-with-no-image ast-product-tabs-layout-horizontal product type-product post-2343 status-publish last instock product_cat-polyurethane-sealant product_cat-windshield-adhesive product_tag-automotive-sealant has-post-thumbnail shipping-taxable product-type-simple\">\n\t<a href=\"https:\/\/joobond.com\/es\/producto\/j-520-adhesivo-de-alta-resistencia-para-parabrisas\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-520-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"J-520 Adhesivo de alta resistencia para parabrisas\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-520-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-520-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-520-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-520-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-520-100x100.webp 100w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/J-520.webp 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">J-520 Adhesivo de alta resistencia para parabrisas<\/h2>\n<\/a><a href=\"https:\/\/joobond.com\/es\/producto\/j-520-adhesivo-de-alta-resistencia-para-parabrisas\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2343\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"2343\" data-product_sku=\"\" aria-label=\"M\u00e1s informaci\u00f3n sobre &quot;J-520 High Strength Windscreen Adhesive\" rel=\"nofollow\" data-success_message=\"\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\">Seguir leyendo<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2343\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5f92c391 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-139d59e0\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-af5499e2\"><h6 class=\"uagb-heading-text\">POR QU\u00c9 ELEGIRNOS<\/h6><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7350a023\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a39d00c5\"><h2 class=\"uagb-heading-text\"><strong>Integraci\u00f3n y automatizaci\u00f3n inteligentes | Calidad probada en el tiempo<\/strong><\/h2><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1914c6be alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f480abf5\">\n<div class=\"wp-block-uagb-info-box uagb-block-8c1b05f8 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/icon-1.00-1-150x150.png\" alt=\"\" width=\"65\" height=\"65\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Escala y capacidad<\/h3><\/div><p class=\"uagb-ifb-desc\">Disponer de amplias instalaciones de producci\u00f3n equipadas con tecnolog\u00eda punta nos permite producir sellantes de silicona a gran escala manteniendo los m\u00e1s altos est\u00e1ndares de calidad.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-96d22959\">\n<div class=\"wp-block-uagb-info-box uagb-block-b2d69344 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/icon-2-1-150x150.png\" alt=\"\" width=\"65\" height=\"65\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Investigaci\u00f3n y desarrollo<\/h3><\/div><p class=\"uagb-ifb-desc\">El equipo de I+D est\u00e1 siempre a la vanguardia de la innovaci\u00f3n, mejorando y desarrollando constantemente nuevas f\u00f3rmulas de sellantes de silicona para satisfacer las necesidades de los mercados emergentes.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d7e7012b\">\n<div class=\"wp-block-uagb-info-box uagb-block-524bae82 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/icon-3.0-150x150.png\" alt=\"\" width=\"65\" height=\"65\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Garant\u00eda de calidad<\/h3><\/div><p class=\"uagb-ifb-desc\">Cumplimos estrictos protocolos de control de calidad, incluida la certificaci\u00f3n ISO y auditor\u00edas peri\u00f3dicas de terceros, para garantizar la fiabilidad y durabilidad de nuestros productos.<\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-52e24014 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-89a30c20\">\n<div class=\"wp-block-uagb-info-box uagb-block-ce13dcb6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/icon-4-150x150.png\" alt=\"\" width=\"65\" height=\"65\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Alcance mundial<\/h3><\/div><p class=\"uagb-ifb-desc\">Gracias a nuestra amplia red de distribuci\u00f3n y a nuestras asociaciones estrat\u00e9gicas, exportamos eficazmente nuestros productos a todo el mundo.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9d98aca1\">\n<div class=\"wp-block-uagb-info-box uagb-block-a676cdba uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/icon-5.0-150x150.png\" alt=\"\" width=\"65\" height=\"65\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Enfoque centrado en el cliente<\/h3><\/div><p class=\"uagb-ifb-desc\">Damos prioridad al servicio al cliente, proporcionando asistencia personalizada, consultor\u00eda t\u00e9cnica y soluciones a medida para satisfacer las necesidades espec\u00edficas de nuestros clientes.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-372ea69a\">\n<div class=\"wp-block-uagb-info-box uagb-block-ba88ddd6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/icon-6-1024x218-1-150x150.png\" alt=\"\" width=\"65\" height=\"65\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Equipamiento de vanguardia<\/h3><\/div><p class=\"uagb-ifb-desc\">Utilizamos equipos de producci\u00f3n l\u00edderes a nivel internacional para garantizar un rendimiento superior de los productos, superar a nuestros competidores y mejorar la calidad de nuestros productos.<\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c9f40731 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-558d00ae\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-73fc2ee9\"><h2 class=\"uagb-heading-text\">Fuerza de f\u00e1brica&nbsp;<\/h2><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">Potencia de producci\u00f3n masiva con eficiencia\uff0cLegado probado en soluciones de silicona, sellantes MS e impermeabilizaci\u00f3n.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e8bd6b4e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-d15b022e\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-uagb-image uagb-block-ecb3ccea wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_01.webp ,https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_01.webp 780w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_01.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_01.webp\" alt=\"\" class=\"uag-image-2301\" width=\"520\" height=\"460\" title=\"f\u00e1brica_01\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0b57ac7e\">\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-bc32a53b\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-4 spectra-image-gallery__layout--grid-col-tab-3 spectra-image-gallery__layout--grid-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1468' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/0b04ed6f-4dd6-4a6f-8675-971b7ec62d68.webp\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/0b04ed6f-4dd6-4a6f-8675-971b7ec62d68-1024x1024.webp\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/0b04ed6f-4dd6-4a6f-8675-971b7ec62d68-300x300.webp\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2222' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_1.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_1.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_1-300x221.png\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2223' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_2.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_2.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_2-300x221.png\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1470' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/92f20941-44d2-4f31-964d-67ab9014110c.webp\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/92f20941-44d2-4f31-964d-67ab9014110c-1024x1024.webp\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/92f20941-44d2-4f31-964d-67ab9014110c-300x300.webp\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1472' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/c6956a21-1287-4f6f-b74e-892e2659d732.webp\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/c6956a21-1287-4f6f-b74e-892e2659d732-1024x1024.webp\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/c6956a21-1287-4f6f-b74e-892e2659d732-300x300.webp\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2225' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_4.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_4.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_4-300x221.png\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2231' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_8-scaled.webp\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_8-1024x768.webp\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_8-300x225.webp\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2224' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_3.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_3.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/factory_3-300x221.png\" alt=\"\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-80d49ee2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5d3eb422\"><p class=\"uagb-desc-text\">Testimonios<\/p><h2 class=\"uagb-heading-text\">Lo que dice la gente<\/h2><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e93f1702 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b4669201\">\n<div class=\"wp-block-uagb-container uagb-block-e87369d3\">\n<div class=\"wp-block-uagb-image uagb-block-865bd391 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/woman-with-black-jacket-avatar.jpg ,https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/woman-with-black-jacket-avatar.jpg 780w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/woman-with-black-jacket-avatar.jpg\" alt=\"\" class=\"uag-image-69\" width=\"203\" height=\"252\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-32c44910\">\n<div class=\"wp-block-uagb-info-box uagb-block-fb798284 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M96 224C84.72 224 74.05 226.3 64 229.9V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32S145.7 96 128 96C57.42 96 0 153.4 0 224v96c0 53.02 42.98 96 96 96s96-42.98 96-96S149 224 96 224zM352 224c-11.28 0-21.95 2.305-32 5.879V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32s-14.33-32-32-32c-70.58 0-128 57.42-128 128v96c0 53.02 42.98 96 96 96s96-42.98 96-96S405 224 352 224z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Despu\u00e9s de probar varias marcas, nos decidimos por Joobond para todos nuestros proyectos de construcci\u00f3n. Sus sellantes superan a los de la competencia en durabilidad y facilidad de aplicaci\u00f3n.<\/p><\/div><p class=\"uagb-ifb-desc\"><strong>Lisa<\/strong> Cynthia<\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6125e5f1\">\n<div class=\"wp-block-uagb-container uagb-block-3fc5dc73\">\n<div class=\"wp-block-uagb-image uagb-block-ea7d81d8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/man-wearing-glasses-avatar.jpg ,https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/man-wearing-glasses-avatar.jpg 780w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/04\/man-wearing-glasses-avatar.jpg\" alt=\"\" class=\"uag-image-68\" width=\"203\" height=\"252\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-15dc585c\">\n<div class=\"wp-block-uagb-info-box uagb-block-36cf55f5 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M96 224C84.72 224 74.05 226.3 64 229.9V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32S145.7 96 128 96C57.42 96 0 153.4 0 224v96c0 53.02 42.98 96 96 96s96-42.98 96-96S149 224 96 224zM352 224c-11.28 0-21.95 2.305-32 5.879V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32s-14.33-32-32-32c-70.58 0-128 57.42-128 128v96c0 53.02 42.98 96 96 96s96-42.98 96-96S405 224 352 224z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Los sellantes PU de Joobond transformaron nuestra l\u00ednea de montaje de autom\u00f3viles. La adherencia superior y la resistencia a la intemperie han reducido nuestros costes de mantenimiento en 30%. Soluciones industriales realmente fiables.<\/p><\/div><p class=\"uagb-ifb-desc\"><strong>Michael<\/strong> Taylor<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9f353843 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-56fcfc1a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Cuando se trata de fiabilidad, \u00a1somos los que necesita!<\/h1><\/div><p class=\"uagb-ifb-desc\">Su socio de confianza para una fiabilidad inigualable.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"https:\/\/joobond.com\/es\/pongase-en-contacto-con\/\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return true;\"><span class=\"uagb-inline-editing\">M\u00e1s informaci\u00f3n<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM358.6 278.6l-112 112c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L290.8 256L201.4 166.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l112 112C364.9 239.6 368 247.8 368 256S364.9 272.4 358.6 278.6z\"><\/path><\/svg><\/a><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6ff30b2d\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-739ccf6c\"><h5 class=\"uagb-heading-text\">Solicitar devoluci\u00f3n de llamada<\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-forms uagb-forms__outer-wrap uagb-block-fbc62094 uagb-forms__medium-btn\"><form class=\"uagb-forms-main-form\" method=\"post\" autocomplete=\"on\" name=\"uagb-form-fbc62094\" action=\"\">\n<div class=\"wp-block-uagb-forms-name uagb-forms-name-wrap uagb-forms-field-set uagb-block-a27f7b51\"><div class=\"uagb-forms-name-label required uagb-forms-input-label\" id=\"a27f7b51\">Nombre<\/div><input type=\"text\" placeholder=\"Su nombre\" required class=\"uagb-forms-name-input uagb-forms-input\" name=\"a27f7b51\" autocomplete=\"given-name\"\/><\/div>\n\n\n\n<div class=\"wp-block-uagb-forms-email uagb-forms-email-wrap uagb-forms-field-set uagb-block-413f8461\"><div class=\"uagb-forms-email-label required uagb-forms-input-label\" id=\"413f8461\">Correo electr\u00f3nico<\/div><input type=\"email\" class=\"uagb-forms-email-input uagb-forms-input\" placeholder=\"Su correo electr\u00f3nico\" required name=\"413f8461\" autocomplete=\"email\"\/><\/div>\n\n\n\n<div class=\"wp-block-uagb-forms-email uagb-forms-email-wrap uagb-forms-field-set uagb-block-2d3efc5a\"><div class=\"uagb-forms-email-label required uagb-forms-input-label\" id=\"2d3efc5a\">Asunto<\/div><input type=\"email\" class=\"uagb-forms-email-input uagb-forms-input\" placeholder=\"N\u00ba de contacto\" required name=\"2d3efc5a\" autocomplete=\"off\"\/><\/div>\n\n\n\n<div class=\"wp-block-uagb-forms-email uagb-forms-email-wrap uagb-forms-field-set uagb-block-d3b06667\"><div class=\"uagb-forms-email-label required uagb-forms-input-label\" id=\"d3b06667\">Asunto<\/div><input type=\"email\" class=\"uagb-forms-email-input uagb-forms-input\" placeholder=\"Objeto del contacto\" required name=\"d3b06667\" autocomplete=\"off\"\/><\/div>\n\n\n\n<div class=\"wp-block-uagb-forms-textarea uagb-forms-textarea-wrap uagb-forms-field-set uagb-block-21604245\"><div class=\"uagb-forms-textarea-label required uagb-forms-input-label\" id=\"21604245\">Mensaje<\/div><textarea required class=\"uagb-forms-textarea-input uagb-forms-input\" rows=\"4\" placeholder=\"Su mensaje\" name=\"21604245\" autocomplete=\"off\"><\/textarea><\/div>\n<div class=\"uagb-forms-form-hidden-data\"><input type=\"hidden\" class=\"uagb_forms_form_label\" value=\"Spectra Form\"\/><input type=\"hidden\" class=\"uagb_forms_form_id\" value=\"uagb-form-fbc62094\"\/><\/div><div class=\"uagb-form-reacaptcha-error-fbc62094\"><\/div><div class=\"uagb-forms-main-submit-button-wrap wp-block-button\"><button class=\"uagb-forms-main-submit-button wp-block-button__link\"><div class=\"uagb-forms-main-submit-button-text\">Solicitar llamada<\/div><\/button><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><div class=\"uagb-forms-success-message-fbc62094 uagb-forms-submit-message-hide\"><span>El formulario se ha enviado correctamente.<\/span><\/div><div class=\"uagb-forms-failed-message-fbc62094 uagb-forms-submit-message-hide\"><span>Se ha producido un error al enviar el formulario. Por favor, compruebe de nuevo todos los campos del formulario.<\/span><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>We Help Your Business Build Stronger Bonds. Our advanced adhesive solutions help industries achieve durable, high-performance results in automotive, construction and manufacturing. Let us strengthen your products. About We are a certified, high-performance adhesive manufacturer. Joobond is a specialized sealant producer committed to delivering superior bonding solutions for your industry. WHY CHOOSE US Smart Integration [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"spectra_gs_classes":"","footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"acf":[],"spectra_custom_meta":{"_customize_changeset_uuid":["91cec1a9-3cc4-48ed-8997-b46a67826cb2"],"site-content-layout":["page-builder"],"site-post-title":["disabled"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["4"],"astra-main-page-id":["74939"],"ast_self_id_74939":["1"],"ast-site-content-layout":["full-width-container"],"site-content-style":["unboxed"],"site-sidebar-style":["unboxed"],"astra-migrate-meta-layouts":["set"],"_wxr_import_user_slug":["aadhavanm"],"_astra_sites_imported_post":["1"],"_astra_sites_enable_for_batch":["1"],"_edit_lock":["1765157655:2"],"_edit_last":["2"],"rank_math_seo_score":["88"],"rank_math_focus_keyword":["Joobond"],"rank_math_description":["Manufacturer of polyurethane, MS &amp; industrial sealants since 2009. Joobond is now a globally trusted supplier with proven expertise."],"wp_statistics_words_count":["354"],"_uag_custom_page_level_css":[""],"_monsterinsights_skip_tracking":[""],"_monsterinsights_sitenote_active":[""],"site-sidebar-layout":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_uag_page_assets":["a:9:{s:3:\"css\";s:353186:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:0.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}\n.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all 0.3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}\n.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow 0.2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:0.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:0.2;background:rgba(0,0,0,0.5);transition:opacity 0.35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:0.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform 0.35s, opacity 0.35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform 0.4s, opacity 0.4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform 0.45s, opacity 0.45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}\n.uagb-ifb-content>svg *{-webkit-transition:all 0.2s;-o-transition:all 0.2s;transition:all 0.2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=\"rtl\"] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}\n.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media (max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media (max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}\n.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow 0.2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}\n\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow 0.25s;-moz-transition:box-shadow 0.25s;-o-transition:box-shadow 0.25s;transition:box-shadow 0.25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:0.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter 0.5s, transform 0.5s;-moz-transition:filter 0.5s, transform 0.5s;-o-transition:filter 0.5s, transform 0.5s;transition:filter 0.5s, transform 0.5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow 0.25s, -webkit-backdrop-filter 0.5s;-moz-transition:box-shadow 0.25s, backdrop-filter 0.5s;-o-transition:box-shadow 0.25s, backdrop-filter 0.5s;transition:box-shadow 0.25s, backdrop-filter 0.5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color, background-color, border-color;-moz-transition-property:color, background-color, border-color;-o-transition-property:color, background-color, border-color;transition-property:color, background-color, border-color;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color 0.25s;-moz-transition:background-color 0.25s;-o-transition:background-color 0.25s;transition:background-color 0.25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:transparent;padding:0;cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-arrows:disabled{opacity:0.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:transparent}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:transparent;border:0;outline:none;background:transparent;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:0.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:0.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-button.disabled{opacity:0.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:0.5em;background-color:transparent;border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0,0,0,0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:0.5;transform:scale(75%);-webkit-transition-property:opacity, transform;-moz-transition-property:opacity, transform;-o-transition-property:opacity, transform;transition-property:opacity, transform;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:transparent;border:none;outline:0;line-height:0;z-index:999;transition:transform 500ms}.spectra-image-gallery__control-lightbox--close:hover,.spectra-image-gallery__control-lightbox--close:focus,.spectra-image-gallery__control-lightbox--close:focus-visible{background-color:transparent;transform:scale(1.25)}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media (max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media (max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}\n.uagb-forms__outer-wrap .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-input::placeholder,.uagb-forms__outer-wrap .uagb-forms-input-label,.uagb-forms__outer-wrap .uagb-forms-main-submit-button,.uagb-forms__outer-wrap .uagb-forms-success-message,.uagb-forms__outer-wrap .uagb-forms-failed-message{-webkit-transition-property:color, background-color, border-color;-moz-transition-property:color, background-color, border-color;-o-transition-property:color, background-color, border-color;transition-property:color, background-color, border-color;-webkit-transition-duration:0.15s;-moz-transition-duration:0.15s;-o-transition-duration:0.15s;transition-duration:0.15s}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=\"text\"]{min-height:0 !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input::-webkit-input-placeholder,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=\"text\"]::-webkit-input-placeholder{overflow:unset}.uagb-forms__outer-wrap .uagb-forms-main-form input:not([type=\"checkbox\"]):not([type=\"radio\"]):not([type=\"file\"]),.uagb-forms__outer-wrap .uagb-forms-main-form textarea,.uagb-forms__outer-wrap .uagb-forms-main-form select{width:100%;box-sizing:border-box}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-checkbox-wrap .uagb-form-checkbox-option input.uagb-inner-input-view{width:33%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-forms-phone-input{width:75% !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%;justify-content:space-between}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .required::after{color:#f00;content:\" *\"}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-form-hidden-data{display:none}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button.wp-block-button__link{width:auto}.uagb-forms__outer-wrap .uagb-forms-submit-message-hide{display:none}.uagb-forms__outer-wrap .uagb-forms-success-message{padding:20px 20px}.uagb-forms__outer-wrap .uagb-forms-failed-message{padding:20px 20px}.uagb-forms__outer-wrap span.components-spinner{float:none}.uagb-forms__outer-wrap .uagb-forms-input.uagb-form-phone-country{background-color:#fff}.uagb-forms__outer-wrap .uag-col-2-wrap{display:grid;grid-template-columns:1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-3-wrap{display:grid;grid-template-columns:1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-4-wrap{display:grid;grid-template-columns:1fr 1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uagb-switch{position:relative;display:inline-block;width:50px;height:25px}.uagb-forms__outer-wrap .uagb-switch input{width:0;height:0;opacity:0}.uagb-forms__outer-wrap .uagb-slider{position:absolute;top:0;right:0;bottom:0;left:0;background-color:#fff;cursor:pointer;transition:0.4s;-webkit-transition:0.4s}.uagb-forms__outer-wrap .uagb-switch .uagb-slider::before{position:absolute;width:20px;height:20px;background-color:#000;transition:0.4s;content:\"\";-webkit-transition:0.4s}.uagb-forms__outer-wrap .uagb-switch input:checked+.uagb-slider::before{background-color:#fff}.uagb-forms__outer-wrap .uagb-slider.round::before{border-radius:50% !important}.uagb-forms-select-box,.uagb-form-phone-country,.uagb-forms-phone-wrap .uagb-forms-phone-input{height:auto;-webkit-appearance:none;appearance:none}.uagb-forms-radio-wrap input[type=\"radio\"]:checked+label::before{line-height:1.2;content:\" \"}.uagb-forms-radio-wrap input[type=\"radio\"]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\"\"}.uagb-forms-radio-wrap input[type=\"radio\"].round+label::before{border-radius:100% !important}select::after,select::before{padding:10px}.uagb-forms-radio-wrap input[type=\"radio\"],.uagb-forms-checkbox-wrap input[type=\"checkbox\"],.uagb-forms-accept-wrap input[type=\"checkbox\"]{opacity:0}.uagb-forms-checkbox-wrap input[type=\"checkbox\"]:checked+label::before,.uagb-forms-accept-wrap input[type=\"checkbox\"]:checked+label::before{line-height:1.2;content:\"\\2714\"}.uagb-forms-checkbox-wrap input[type=\"checkbox\"]+label::before,.uagb-forms-accept-wrap input[type=\"checkbox\"]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\" \"}@media only screen and (max-width: 767px){.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%}}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-20 .uagb-forms-main-form{column-gap:20px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-15 .uagb-forms-main-form{column-gap:15px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-10 .uagb-forms-main-form{column-gap:10px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-5 .uagb-forms-main-form{column-gap:5px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-flex-start .uagb-forms-main-form{align-items:flex-start}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-center .uagb-forms-main-form{align-items:center}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form{display:flex;flex-wrap:wrap;margin:0 -5px;position:relative;text-align:left}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-80{width:80%}@media (min-width: 768px) and (max-width: 1024px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}@media (max-width: 767px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}\n.wp-block-uagb-container.uagb-block-7d5944be .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7d5944be .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7d5944be .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7d5944be .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7d5944be .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7d5944be{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-7d5944be{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;max-width: 100% !important;}.wp-block-uagb-container.uagb-block-a6e5678a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a6e5678a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a6e5678a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a6e5678a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a6e5678a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6e5678a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6e5678a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a6e5678a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-72888ee5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-72888ee5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-72888ee5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-72888ee5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-72888ee5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72888ee5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-72888ee5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-72888ee5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2169cbd9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2169cbd9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2169cbd9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2169cbd9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2169cbd9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2169cbd9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2169cbd9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1400px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2169cbd9{box-shadow: 0px 0px   #00000070 ;padding-top: 80px;padding-bottom: 80px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-356613ba .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-356613ba .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-356613ba .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-356613ba .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-356613ba .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-356613ba{max-width: 60%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-356613ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-356613ba{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e986d9d5.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e986d9d5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e986d9d5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e986d9d5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e986d9d5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-34dff01e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-34dff01e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-34dff01e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-34dff01e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-34dff01e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34dff01e{max-width: 40%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34dff01e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-34dff01e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 50px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d9cb8524.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d9cb8524.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9cb8524.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9cb8524.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d9cb8524 .uagb-heading-text{margin-bottom: 0px;}.wp-block-uagb-container.uagb-block-a9633eaa .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a9633eaa .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a9633eaa .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a9633eaa .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a9633eaa .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a9633eaa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a9633eaa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1400px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a9633eaa{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background: linear-gradient(180deg, var(--ast-global-color-5) 75%, var(--ast-global-color-2) 0%);;background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-44c89d1e.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-44c89d1e.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-44c89d1e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 1140px;height: auto;}.uagb-block-44c89d1e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-44c89d1e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-926b8013 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926b8013 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926b8013 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-926b8013 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-926b8013 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926b8013{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926b8013 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1400px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-926b8013{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-style: none;border-color: inherit;background: linear-gradient(360deg, var(--ast-global-color-5) 55%, var(--ast-global-color-2) 0%);;background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-bcbb6009 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bcbb6009 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bcbb6009 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bcbb6009 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bcbb6009 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bcbb6009{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bcbb6009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-bcbb6009{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1eef76a8.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-1eef76a8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1eef76a8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1eef76a8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1eef76a8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-4);}.wp-block-uagb-advanced-heading.uagb-block-aa57526f.wp-block-uagb-advanced-heading .uagb-desc-text{color: #cfcfcf;margin-bottom: 40px;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f .uagb-heading-text{margin-bottom: 20px;}.uagb-block-dab7cfbd.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-dab7cfbd .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-dab7cfbd.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-dab7cfbd.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-dab7cfbd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 650px;height: 450px;}.uagb-block-dab7cfbd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-dab7cfbd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-dab7cfbd.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-05d59665 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-05d59665 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-05d59665 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-05d59665 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-05d59665 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-05d59665{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-05d59665 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-05d59665{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 30px;column-gap: 0px;}.uagb-block-261d01ec.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-261d01ec .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-261d01ec.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-261d01ec.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-261d01ec.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-261d01ec.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 650px;height: 450px;}.uagb-block-261d01ec.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-261d01ec.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-261d01ec.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-261d01ec.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-0c48022c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0c48022c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-0c48022c .uagb-ifb-icon svg{fill: #333;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0c48022c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0c48022c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0c48022c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0c48022c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-0c48022c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0c48022c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0c48022c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-0c48022c.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-0c48022c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-0c48022c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-0c48022c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-0c48022c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-0c48022c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0c48022c .uagb-infobox__content-wrap{text-align: left;}.uagb-block-0c48022c.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-0c48022c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0c48022c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-73d6529f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-73d6529f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-73d6529f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-73d6529f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-73d6529f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-73d6529f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-73d6529f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-73d6529f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a7328e4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a7328e4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a7328e4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a7328e4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a7328e4 .uagb-container__video-wrap video{opacity: 0.35;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a7328e4{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a7328e4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a7328e4{box-shadow: 0px 0px   #00000070 ;padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 57% 57%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Curtain.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a7328e4::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #FFFFFF75;opacity: 0.65;}.uagb-block-897ad235.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-897ad235.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-897ad235 .uagb-buttons-repeater:not(.wp-block-button__link){letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-897ad235 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-897ad235 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-897ad235 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-93af6ed7 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-93af6ed7 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-93af6ed7 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: #a9ba20;}.wp-block-uagb-buttons .uagb-block-93af6ed7 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: #a9ba20;}.wp-block-uagb-buttons .uagb-block-93af6ed7 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-93af6ed7 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-container.uagb-block-2659f406 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2659f406 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2659f406 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2659f406 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2659f406 .uagb-container__video-wrap video{opacity: 0.35;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2659f406{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2659f406 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2659f406{box-shadow: 0px 0px   #00000070 ;padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Interior.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2659f406::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #FFFFFF75;opacity: 0.65;}.uagb-block-6e1a09f0.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-6e1a09f0.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-6e1a09f0 .uagb-buttons-repeater:not(.wp-block-button__link){letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-6e1a09f0 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-6e1a09f0 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-6e1a09f0 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-fd369e15 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-fd369e15 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-fd369e15 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-fd369e15 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-fd369e15 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-fd369e15 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-container.uagb-block-06538a18 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-06538a18 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-06538a18 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-06538a18 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-06538a18 .uagb-container__video-wrap video{opacity: 0.35;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-06538a18{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-06538a18 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-06538a18{box-shadow: 0px 0px   #00000070 ;padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Automotive.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-06538a18::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #FFFFFF75;opacity: 0.65;}.uagb-block-36618dbf.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-36618dbf.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-36618dbf .uagb-buttons-repeater:not(.wp-block-button__link){letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-36618dbf .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-36618dbf .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-36618dbf .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-2b3de640 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-2b3de640 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-2b3de640 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-2b3de640 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-2b3de640 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-2b3de640 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-container.uagb-block-8ddbcb7a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8ddbcb7a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8ddbcb7a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8ddbcb7a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8ddbcb7a .uagb-container__video-wrap video{opacity: 0.35;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8ddbcb7a{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8ddbcb7a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8ddbcb7a{box-shadow: 0px 0px   #00000070 ;padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Window.webp);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8ddbcb7a::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #FFFFFF75;opacity: 0.65;}.uagb-block-7b9b18e7.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-7b9b18e7.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-7b9b18e7 .uagb-buttons-repeater:not(.wp-block-button__link){letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-7b9b18e7 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-7b9b18e7 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{letter-spacing: 0px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-7b9b18e7 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-a4ce54b0 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-a4ce54b0 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-a4ce54b0 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-a4ce54b0 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-a4ce54b0 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-a4ce54b0 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-container.uagb-block-e2755050 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e2755050 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e2755050 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e2755050 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e2755050 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e2755050{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e2755050 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e2755050{box-shadow: 0px 0px   #00000070 ;padding-top: 84px;padding-bottom: 64px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1c410426 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1c410426 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1c410426 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1c410426 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1c410426 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c410426{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c410426 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1c410426{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-a3371d64.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a3371d64.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a3371d64.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a3371d64.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-a3371d64.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a3371d64.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-a3371d64.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a3371d64.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-80693cba .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80693cba .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80693cba .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80693cba .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80693cba .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80693cba{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80693cba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-80693cba{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 80px;padding-right: 88px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-84cb56a6 .uagb-ifb-icon{width: 28px;line-height: 28px;}.uagb-block-84cb56a6 .uagb-ifb-icon > span{font-size: 28px;width: 28px;line-height: 28px;color: var(--ast-global-color-0);}.uagb-block-84cb56a6 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 28px;height: 28px;line-height: 28px;font-size: 28px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-84cb56a6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 28px;font-size: 28px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-84cb56a6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 28px;height: 28px;line-height: 28px;padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-84cb56a6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 28px;line-height: 28px;font-size: 28px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-84cb56a6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 28px;line-height: 28px;font-size: 28px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-84cb56a6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;}.uagb-block-84cb56a6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;border-radius: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;border-radius: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;border-radius: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 14px;padding-right: 14px;padding-top: 14px;padding-bottom: 14px;border-radius: 0px;}.uagb-block-84cb56a6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 36px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-84cb56a6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-84cb56a6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-84cb56a6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-84cb56a6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-84cb56a6 .uagb-ifb-title-prefix{text-transform: uppercase;font-size: 12px;letter-spacing: 2px;}[dir=rtl] .uagb-block-84cb56a6 .uagb-iconbox-icon-wrap{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 14px;padding-left: 14px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-267e3d1f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-267e3d1f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-267e3d1f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-267e3d1f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-267e3d1f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-267e3d1f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-267e3d1f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-267e3d1f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 104px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5f92c391 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f92c391 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f92c391 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5f92c391 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5f92c391 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f92c391{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f92c391 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5f92c391{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 60px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-139d59e0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-139d59e0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-139d59e0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-139d59e0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-139d59e0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-139d59e0{max-width: 30%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-139d59e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-139d59e0{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-af5499e2.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-af5499e2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-af5499e2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af5499e2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af5499e2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-7350a023 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7350a023 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7350a023 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7350a023 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7350a023 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7350a023{max-width: 70%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7350a023 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7350a023{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a39d00c5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a39d00c5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a39d00c5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a39d00c5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a39d00c5 .uagb-heading-text{line-height: 1.2em;}.wp-block-uagb-container.uagb-block-1914c6be .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1914c6be .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1914c6be .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1914c6be .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1914c6be .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1914c6be{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1914c6be > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1400px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1914c6be{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f480abf5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f480abf5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f480abf5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f480abf5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f480abf5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f480abf5{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f480abf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f480abf5{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;overflow: visible;order: initial;border-color: inherit;background-color: #108847;;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-8c1b05f8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-8c1b05f8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8c1b05f8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8c1b05f8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-8c1b05f8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-8c1b05f8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-8c1b05f8.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;}.uagb-block-8c1b05f8.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-8c1b05f8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-8c1b05f8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-8c1b05f8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8c1b05f8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap{border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-8c1b05f8 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-8c1b05f8.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 15px;padding-right: 15px;padding-bottom: 15px;padding-left: 15px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 15px;padding-right: 15px;padding-bottom: 15px;padding-left: 15px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-image-content > img{width: 65px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 65px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 65px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 65px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8c1b05f8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-96d22959 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-96d22959 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-96d22959 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-96d22959 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-96d22959 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-96d22959{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-96d22959 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-96d22959{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;overflow: visible;order: initial;border-style: solid;border-color: inherit;background-color: ;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-b2d69344 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b2d69344 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-b2d69344 .uagb-ifb-icon svg{fill: #333;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b2d69344 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-b2d69344 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-b2d69344 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b2d69344.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-b2d69344 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b2d69344.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-b2d69344.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-b2d69344 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b2d69344 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b2d69344 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b2d69344 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b2d69344 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b2d69344.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-image-content > img{width: 65px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 65px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 65px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 65px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b2d69344 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-d7e7012b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d7e7012b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d7e7012b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d7e7012b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d7e7012b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d7e7012b{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d7e7012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d7e7012b{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;overflow: visible;order: initial;border-color: inherit;background-color: #108847;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-524bae82 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-524bae82 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-524bae82 .uagb-ifb-icon svg{fill: #333;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-524bae82 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-524bae82 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-524bae82 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-524bae82.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-524bae82 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-524bae82.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 10px;}.uagb-block-524bae82.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-524bae82 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-524bae82 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-524bae82 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-524bae82 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-524bae82 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-524bae82.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-image-content > img{width: 65px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 65px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 65px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 65px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-524bae82 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-524bae82.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-52e24014 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-52e24014 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-52e24014 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-52e24014 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-52e24014 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52e24014{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52e24014 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1400px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-52e24014{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-89a30c20 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89a30c20 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89a30c20 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89a30c20 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89a30c20 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89a30c20{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89a30c20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-89a30c20{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;overflow: visible;order: initial;border-style: solid;border-color: inherit;background-color: ;;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-ce13dcb6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-ce13dcb6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ce13dcb6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ce13dcb6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ce13dcb6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ce13dcb6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ce13dcb6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;}.uagb-block-ce13dcb6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-ce13dcb6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ce13dcb6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ce13dcb6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ce13dcb6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap{border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;}.uagb-block-ce13dcb6 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-ce13dcb6.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 15px;padding-right: 15px;padding-bottom: 15px;padding-left: 15px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 15px;padding-right: 15px;padding-bottom: 15px;padding-left: 15px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-image-content > img{width: 65px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 65px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 65px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 65px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ce13dcb6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-9d98aca1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9d98aca1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9d98aca1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9d98aca1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9d98aca1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d98aca1{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d98aca1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9d98aca1{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;overflow: visible;order: initial;border-color: inherit;background-color: #108847;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-a676cdba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a676cdba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-a676cdba .uagb-ifb-icon svg{fill: #333;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a676cdba .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a676cdba .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-a676cdba .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-a676cdba.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-a676cdba .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-a676cdba.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-a676cdba.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-a676cdba .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-a676cdba .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-a676cdba .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-a676cdba .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a676cdba .uagb-infobox__content-wrap{text-align: left;}.uagb-block-a676cdba.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-image-content > img{width: 65px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 65px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 65px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 65px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a676cdba .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-372ea69a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-372ea69a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-372ea69a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-372ea69a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-372ea69a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-372ea69a{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-372ea69a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-372ea69a{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;overflow: visible;order: initial;border-style: solid;border-color: inherit;background-color: ;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-ba88ddd6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-ba88ddd6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ba88ddd6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-ba88ddd6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;}.uagb-block-ba88ddd6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 30px;border-radius: 0px;}.uagb-block-ba88ddd6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ba88ddd6.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;}.uagb-block-ba88ddd6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-ba88ddd6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ba88ddd6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ba88ddd6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ba88ddd6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ba88ddd6 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-ba88ddd6.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-image-content > img{width: 65px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 65px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 65px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 65px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ba88ddd6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-c9f40731 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c9f40731 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c9f40731 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c9f40731 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c9f40731 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c9f40731{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c9f40731 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c9f40731{min-height: 200px;box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-558d00ae .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-558d00ae .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-558d00ae .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-558d00ae .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-558d00ae .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-558d00ae{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-558d00ae > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-558d00ae{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-73fc2ee9.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-73fc2ee9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-73fc2ee9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-73fc2ee9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-73fc2ee9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-e8bd6b4e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8bd6b4e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8bd6b4e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8bd6b4e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8bd6b4e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8bd6b4e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8bd6b4e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1400px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e8bd6b4e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d15b022e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d15b022e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d15b022e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d15b022e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d15b022e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d15b022e{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d15b022e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d15b022e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-ecb3ccea.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-width: 7px;border-left-width: 7px;border-right-width: 7px;border-bottom-width: 7px;border-style: solid;border-color: #108847;}.uagb-block-ecb3ccea.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-width: 7px;border-left-width: 7px;border-right-width: 7px;border-bottom-width: 7px;border-style: solid;border-color: #108847;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-width: 7px;border-left-width: 7px;border-right-width: 7px;border-bottom-width: 7px;border-style: solid;border-color: #108847;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-ecb3ccea.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-ecb3ccea.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 520px;height: 460px;}.uagb-block-ecb3ccea.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-ecb3ccea.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-0b57ac7e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0b57ac7e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0b57ac7e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0b57ac7e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0b57ac7e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0b57ac7e{max-width: 70%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0b57ac7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0b57ac7e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-bc32a53b.wp-block-uagb-image-gallery{padding: 30px 30px 30px 30px;}.uagb-block-bc32a53b .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-bc32a53b .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-bc32a53b .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-bc32a53b .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-bc32a53b .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-bc32a53b .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-bc32a53b .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-bc32a53b .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-bc32a53b .spectra-image-gallery__layout--grid{grid-gap: 10px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--isogrid{margin: -5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--masonry{margin: -5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--tiled{grid-gap: 10px;}.uagb-block-bc32a53b .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-bc32a53bspectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-bc32a53b .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-bc32a53b .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-80d49ee2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80d49ee2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80d49ee2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-80d49ee2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-80d49ee2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80d49ee2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80d49ee2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-end;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-80d49ee2{box-shadow: 0px 0px   #00000070 ;padding-top: 84px;padding-bottom: 48px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-1);margin-bottom: 24px;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422 .uagb-heading-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422 .uagb-desc-text{text-transform: uppercase;font-size: 12px;letter-spacing: 2px;}.wp-block-uagb-container.uagb-block-e93f1702 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e93f1702 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e93f1702 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e93f1702 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e93f1702 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e93f1702{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e93f1702 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 32px;}.wp-block-uagb-container.uagb-block-e93f1702{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 104px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 32px;}.wp-block-uagb-container.uagb-block-b4669201 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b4669201 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b4669201 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b4669201 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b4669201 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4669201{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4669201 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b4669201{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 32px !important;margin-bottom: 0px !important;margin-left: 32px;margin-right: 32px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e87369d3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e87369d3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e87369d3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e87369d3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e87369d3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e87369d3{max-width: 32%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e87369d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e87369d3{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-865bd391.wp-block-uagb-image{margin-top: -32px;margin-right: 0px;margin-bottom: 0px;margin-left: -32px;}.uagb-block-865bd391.wp-block-uagb-image--layout-default figure img{box-shadow: 16px 24px 80px -16px rgba(0,0,0,0.4);}.uagb-block-865bd391.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay figure img{box-shadow: 16px 24px 80px -16px rgba(0,0,0,0.4);}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-865bd391.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-865bd391.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-865bd391.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-865bd391.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-865bd391.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 rgba(0,0,0,0.4);}.uagb-block-865bd391.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 rgba(0,0,0,0.4);}.wp-block-uagb-container.uagb-block-32c44910 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-32c44910 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-32c44910 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-32c44910 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-32c44910 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-32c44910{max-width: 68%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-32c44910 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-32c44910{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-fb798284 .uagb-ifb-icon{width: 12px;line-height: 12px;}.uagb-block-fb798284 .uagb-ifb-icon > span{font-size: 12px;width: 12px;line-height: 12px;color: #333;}.uagb-block-fb798284 .uagb-ifb-icon svg{fill: #333;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 12px;height: 12px;line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-fb798284 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-fb798284 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 12px;height: 12px;line-height: 12px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fb798284 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 12px;line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-fb798284 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 12px;line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-fb798284 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fb798284 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-fb798284.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fb798284 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-fb798284.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-fb798284.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fb798284 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fb798284 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fb798284 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fb798284 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fb798284 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-fb798284.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fb798284 .uagb-ifb-desc{font-weight: 600;font-size: 16px;letter-spacing: 1px;}[dir=rtl] .uagb-block-fb798284 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-fb798284.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-6125e5f1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6125e5f1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6125e5f1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6125e5f1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6125e5f1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6125e5f1{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6125e5f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6125e5f1{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 32px !important;margin-bottom: 0px !important;margin-left: 32px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3fc5dc73 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3fc5dc73 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3fc5dc73 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3fc5dc73 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3fc5dc73 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3fc5dc73{max-width: 32%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3fc5dc73 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3fc5dc73{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-ea7d81d8.wp-block-uagb-image{margin-top: -32px;margin-right: 0px;margin-bottom: 0px;margin-left: -32px;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-default figure img{box-shadow: 16px 24px 80px -16px rgba(0,0,0,0.4);}.uagb-block-ea7d81d8.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay figure img{box-shadow: 16px 24px 80px -16px rgba(0,0,0,0.4);}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-ea7d81d8.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-ea7d81d8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-ea7d81d8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-ea7d81d8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 rgba(0,0,0,0.4);}.uagb-block-ea7d81d8.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 rgba(0,0,0,0.4);}.wp-block-uagb-container.uagb-block-15dc585c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15dc585c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15dc585c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-15dc585c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-15dc585c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-15dc585c{max-width: 68%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15dc585c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-15dc585c{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-36cf55f5 .uagb-ifb-icon{width: 12px;line-height: 12px;}.uagb-block-36cf55f5 .uagb-ifb-icon > span{font-size: 12px;width: 12px;line-height: 12px;color: #333;}.uagb-block-36cf55f5 .uagb-ifb-icon svg{fill: #333;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 12px;height: 12px;line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-36cf55f5 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-36cf55f5 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 12px;height: 12px;line-height: 12px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-36cf55f5 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 12px;line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-36cf55f5 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 12px;line-height: 12px;font-size: 12px;color: #333;fill: #333;}.uagb-block-36cf55f5 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-36cf55f5 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-36cf55f5 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-36cf55f5.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-36cf55f5.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-36cf55f5 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-36cf55f5 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-36cf55f5 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-36cf55f5 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-36cf55f5 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-36cf55f5.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-36cf55f5 .uagb-ifb-desc{font-weight: 600;font-size: 16px;letter-spacing: 1px;}[dir=rtl] .uagb-block-36cf55f5 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-9f353843 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f353843 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f353843 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f353843 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f353843 .uagb-container__video-wrap video{opacity: 0.14;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f353843{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f353843 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9f353843{box-shadow: 0px 0px   #00000070 ;padding-top: 120px;padding-bottom: 120px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Scenario-2.webp);background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9f353843::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #108847;opacity: 0.86;}.uagb-block-56fcfc1a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-56fcfc1a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-56fcfc1a .uagb-ifb-icon svg{fill: #333;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-56fcfc1a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-56fcfc1a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-56fcfc1a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-56fcfc1a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-56fcfc1a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-56fcfc1a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-56fcfc1a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-56fcfc1a.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-56fcfc1a.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 44px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-56fcfc1a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-56fcfc1a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-56fcfc1a .uagb-ifb-align-icon-after{margin-left: 10px;}.uagb-block-56fcfc1a .uagb-ifb-align-icon-before{margin-right: 10px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-56fcfc1a .uagb-infobox__content-wrap{text-align: left;}.uagb-block-56fcfc1a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 100px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 100px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 10px;}[dir=rtl] .uagb-block-56fcfc1a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 10px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-6ff30b2d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6ff30b2d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6ff30b2d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6ff30b2d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6ff30b2d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6ff30b2d{max-width: 40%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6ff30b2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6ff30b2d{box-shadow: 0px 0px 40px 1px rgba(0,137,228,0.59) ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 20px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-fbc62094.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fbc62094 .uagb-forms-main-form textarea{text-align: left;}.uagb-block-fbc62094 .uagb-forms-input{text-align: left;}.uagb-block-fbc62094 .uagb-forms-input-label{display: none;text-align: left;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 20px;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input-label{font-weight: 700;font-size: 16px;line-height: 1.1em;color: var(--ast-global-color-3);margin-bottom: 10px;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color: #ffffff !important;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color: #75757e !important;}.uagb-block-fbc62094 .uagb-forms-field-set:hover .uagb-forms-input{background-color: #ffffff;}.uagb-block-fbc62094 .uagb-forms-field-set:hover .uagb-forms-input::placeholder{color: #75757e;}.uagb-block-fbc62094 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-fbc62094 .uagb-form-phone-country{background: url(data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;color: #75757e;}.uagb-block-fbc62094 .uagb-forms-field-set:hover .uagb-form-phone-country{color: #75757e;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-fbc62094 .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-fbc62094 .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-fbc62094 .uagb-slider{background-color: #ffffff;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: #1e1e1e;border-radius: 3px 3px 3px 3px;}.uagb-block-fbc62094 .uagb-switch input:checked + .uagb-slider{background-color: #017cba;}.uagb-block-fbc62094 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: #ffffff;}.uagb-block-fbc62094 .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1px#017cba;}.uagb-block-fbc62094 .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input{background-color: #ffffff;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #dddddd;border-style: solid;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-fbc62094 .uagb-forms-input::placeholder{color: #75757e;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-input{padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-fbc62094 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: #ffffff;box-shadow: inset 0 0 0 4px #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7d5944be{width: 100%;}.wp-block-uagb-container.uagb-block-7d5944be{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: center;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6e5678a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6e5678a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a6e5678a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72888ee5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-72888ee5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-72888ee5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2169cbd9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2169cbd9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-2169cbd9{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-356613ba{max-width: 60%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-356613ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-356613ba{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-356613ba.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-356613ba.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-e986d9d5.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34dff01e{max-width: 40%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34dff01e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-34dff01e{padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a9633eaa{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a9633eaa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a9633eaa{padding-top: 0px;padding-bottom: 0px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background: linear-gradient(180deg, var(--ast-global-color-5) 75%, var(--ast-global-color-2) 0%);;background-clip: padding-box;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-44c89d1e.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1140px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926b8013{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926b8013 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-926b8013{padding-top: 100px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: none;background: linear-gradient(360deg, var(--ast-global-color-5) 55%, var(--ast-global-color-2) 0%);;background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bcbb6009{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bcbb6009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 20px;}.wp-block-uagb-container.uagb-block-bcbb6009{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f .uagb-heading-text{margin-bottom: 20px;}.uagb-block-dab7cfbd.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 650px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-05d59665{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-05d59665 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 20px;}.wp-block-uagb-container.uagb-block-05d59665{padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 20px;}.uagb-block-261d01ec.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 650px;height: auto;}.uagb-block-0c48022c.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-0c48022c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 30px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0c48022c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0c48022c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0c48022c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0c48022c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0c48022c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0c48022c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-73d6529f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-73d6529f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-73d6529f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-block-73d6529f.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-73d6529f.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a7328e4{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a7328e4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;}.wp-block-uagb-container.uagb-block-4a7328e4{padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Curtain.webp);background-clip: padding-box;align-items: flex-start;}.wp-block-uagb-container.uagb-block-4a7328e4::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-897ad235.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-897ad235.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2659f406{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2659f406 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;}.wp-block-uagb-container.uagb-block-2659f406{padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Interior.webp);background-clip: padding-box;align-items: flex-start;}.wp-block-uagb-container.uagb-block-2659f406::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-6e1a09f0.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-6e1a09f0.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-06538a18{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-06538a18 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;}.wp-block-uagb-container.uagb-block-06538a18{padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Automotive.webp);background-clip: padding-box;align-items: flex-start;}.wp-block-uagb-container.uagb-block-06538a18::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-36618dbf.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-36618dbf.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8ddbcb7a{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8ddbcb7a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;}.wp-block-uagb-container.uagb-block-8ddbcb7a{padding-top: 420px;padding-bottom: 40px;padding-left: 40px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Window.webp);background-clip: padding-box;align-items: flex-start;}.wp-block-uagb-container.uagb-block-8ddbcb7a::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-7b9b18e7.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-7b9b18e7.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e2755050{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e2755050 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;}.wp-block-uagb-container.uagb-block-e2755050{padding-top: 50px;padding-bottom: 50px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-block-e2755050.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-e2755050.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c410426{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c410426 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1c410426{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-a3371d64.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80693cba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80693cba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-80693cba{padding-top: 40px;padding-bottom: 0px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-84cb56a6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 40px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 28px;height: 28px;line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-84cb56a6 .uagb-ifb-icon{width: 28px;line-height: 28px;}.uagb-block-84cb56a6 .uagb-ifb-icon > span{font-size: 28px;width: 28px;line-height: 28px;}.uagb-block-84cb56a6 .uagb-iconbox-icon-wrap{width: 28px;height: 28px;line-height: 28px;}.uagb-block-84cb56a6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 28px;line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 28px;line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6 .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-84cb56a6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-267e3d1f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-267e3d1f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-267e3d1f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 80px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f92c391{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f92c391 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-5f92c391{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-139d59e0{max-width: 30%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-139d59e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-139d59e0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-139d59e0.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-139d59e0.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7350a023{max-width: 70%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7350a023 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7350a023{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7350a023.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-7350a023.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1914c6be{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1914c6be > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-1914c6be{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f480abf5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f480abf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-f480abf5{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;background-color: #108847;;align-items: stretch;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8c1b05f8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8c1b05f8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-96d22959{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-96d22959 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-96d22959{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;border-style: solid;background-color: ;;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b2d69344 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b2d69344 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b2d69344 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d7e7012b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d7e7012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d7e7012b{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;background-color: #108847;;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-524bae82 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-524bae82 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-524bae82 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52e24014{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52e24014 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-52e24014{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89a30c20{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89a30c20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-89a30c20{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;border-style: solid;background-color: ;;align-items: stretch;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ce13dcb6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ce13dcb6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d98aca1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d98aca1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9d98aca1{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;background-color: #108847;;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a676cdba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a676cdba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a676cdba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-372ea69a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-372ea69a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-372ea69a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;border-style: solid;background-color: ;;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ba88ddd6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ba88ddd6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c9f40731{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c9f40731 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c9f40731{padding-top: 20px;padding-bottom: 0px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-558d00ae{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-558d00ae > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-558d00ae{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8bd6b4e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8bd6b4e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-e8bd6b4e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d15b022e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d15b022e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-d15b022e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-default figure img{border-style: solid;border-color: #108847;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay figure img{border-style: solid;border-color: #108847;}.uagb-block-ecb3ccea.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 520px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0b57ac7e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0b57ac7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-0b57ac7e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: center;}.uagb-block-bc32a53b.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-bc32a53b .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-bc32a53b .spectra-image-gallery__control-button{padding:    ;}.uagb-block-bc32a53b .spectra-image-gallery__layout--grid{grid-gap: 10px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--isogrid{margin: -5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--masonry{margin: -5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 10px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -10px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--tiled{grid-gap: 10px;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80d49ee2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80d49ee2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-80d49ee2{padding-top: 104px;padding-bottom: 64px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e93f1702{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e93f1702 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e93f1702{padding-top: 0px;padding-bottom: 80px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-block-e93f1702.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-e93f1702.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4669201{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4669201 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;justify-content: center;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b4669201{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 32px !important;margin-bottom: 48px !important;margin-left: 32px;margin-right: 104px;order: initial;align-items: stretch;justify-content: center;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e87369d3{max-width: 32%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e87369d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e87369d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-865bd391.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 203px;height: auto;}.uagb-block-865bd391.wp-block-uagb-image{margin-top: -32px;margin-right: 0px;margin-bottom: 0px;margin-left: -32px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-865bd391 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-32c44910{max-width: 62%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-32c44910 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-32c44910{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 12px;height: 12px;line-height: 12px;font-size: 12px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 12px;font-size: 12px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fb798284 .uagb-ifb-icon{width: 12px;line-height: 12px;}.uagb-block-fb798284 .uagb-ifb-icon > span{font-size: 12px;width: 12px;line-height: 12px;}.uagb-block-fb798284 .uagb-iconbox-icon-wrap{width: 12px;height: 12px;line-height: 12px;}.uagb-block-fb798284 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-fb798284 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fb798284 .uagb-ifb-title{font-size: 16px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6125e5f1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6125e5f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;justify-content: center;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6125e5f1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 32px !important;margin-bottom: 0px !important;margin-left: 32px;margin-right: 104px;order: initial;align-items: stretch;justify-content: center;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3fc5dc73{max-width: 32%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3fc5dc73 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3fc5dc73{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-ea7d81d8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 203px;height: auto;}.uagb-block-ea7d81d8.wp-block-uagb-image{margin-top: -32px;margin-right: 0px;margin-bottom: 0px;margin-left: -32px;text-align: right;justify-content: flex-end;align-self: flex-end;}.uagb-block-ea7d81d8 .wp-block-uagb-image__figure{align-items: flex-end;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-15dc585c{max-width: 62%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15dc585c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-15dc585c{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 12px;height: 12px;line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-36cf55f5 .uagb-ifb-icon{width: 12px;line-height: 12px;}.uagb-block-36cf55f5 .uagb-ifb-icon > span{font-size: 12px;width: 12px;line-height: 12px;}.uagb-block-36cf55f5 .uagb-iconbox-icon-wrap{width: 12px;height: 12px;line-height: 12px;}.uagb-block-36cf55f5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-36cf55f5 .uagb-ifb-title{font-size: 16px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f353843{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f353843 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-9f353843{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Scenario-2.webp);background-clip: padding-box;row-gap: 0px;column-gap: 50px;}.wp-block-uagb-container.uagb-block-9f353843::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #108847;opacity: 0.86;}.uagb-block-56fcfc1a.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-56fcfc1a.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 44px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-56fcfc1a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-56fcfc1a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-56fcfc1a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-56fcfc1a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 10px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 10px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6ff30b2d{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6ff30b2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6ff30b2d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-4);;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.uagb-block-fbc62094.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-fbc62094 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-fbc62094 .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #dddddd;}.uagb-block-fbc62094 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-fbc62094 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7d5944be{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-7d5944be{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: center;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6e5678a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6e5678a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a6e5678a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72888ee5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-72888ee5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-72888ee5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2169cbd9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2169cbd9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2169cbd9{padding-top: 30px;padding-bottom: 44px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-356613ba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-356613ba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-356613ba{padding-top: 0px;padding-bottom: 20px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-e986d9d5.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-34dff01e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-34dff01e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-34dff01e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a9633eaa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a9633eaa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a9633eaa{padding-top: 0px;padding-bottom: 0px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background: linear-gradient(180deg, var(--ast-global-color-5) 75%, var(--ast-global-color-2) 0%);;background-clip: padding-box;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-44c89d1e.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-44c89d1e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 300px;height: 169px;}.uagb-block-44c89d1e.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-44c89d1e .wp-block-uagb-image__figure{align-items: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-926b8013{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-926b8013 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-926b8013{padding-top: 32px;padding-bottom: 32px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: none;background: linear-gradient(360deg, var(--ast-global-color-5) 55%, var(--ast-global-color-2) 0%);;background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bcbb6009{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bcbb6009 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-bcbb6009{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 30px;}.wp-block-uagb-advanced-heading.uagb-block-aa57526f .uagb-heading-text{margin-bottom: 20px;}.uagb-block-dab7cfbd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 800px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-05d59665{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-05d59665 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column-reverse;flex-wrap: wrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-05d59665{padding-top: 50px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;column-gap: 0px;order: initial;flex-direction: column-reverse;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-05d59665.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-05d59665.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-261d01ec.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 800px;height: 300px;}.uagb-block-0c48022c.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-0c48022c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0c48022c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0c48022c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0c48022c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0c48022c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0c48022c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0c48022c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0c48022c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-73d6529f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-73d6529f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-73d6529f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a7328e4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a7328e4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4a7328e4{padding-top: 300px;padding-bottom: 30px;padding-left: 30px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Curtain.webp);background-clip: padding-box;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4a7328e4::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-897ad235.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-897ad235.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2659f406{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2659f406 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2659f406{padding-top: 300px;padding-bottom: 30px;padding-left: 30px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Interior.webp);background-clip: padding-box;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2659f406::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-6e1a09f0.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-6e1a09f0.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-06538a18{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-06538a18 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-06538a18{padding-top: 300px;padding-bottom: 30px;padding-left: 30px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Automotive.webp);background-clip: padding-box;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-06538a18::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-36618dbf.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-36618dbf.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8ddbcb7a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8ddbcb7a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8ddbcb7a{padding-top: 300px;padding-bottom: 30px;padding-left: 30px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Window.webp);background-clip: padding-box;align-items: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8ddbcb7a::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #FFFFFF75;opacity: 0.65;}.uagb-block-7b9b18e7.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-7b9b18e7.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e2755050{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e2755050 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e2755050{padding-top: 64px;padding-bottom: 34px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1c410426{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1c410426 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1c410426{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-a3371d64.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80693cba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80693cba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-80693cba{padding-top: 32px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-84cb56a6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 14px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-84cb56a6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 32px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 28px;height: 28px;line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 28px;line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 28px;line-height: 28px;font-size: 28px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-84cb56a6 .uagb-ifb-icon{width: 28px;line-height: 28px;}.uagb-block-84cb56a6 .uagb-ifb-icon > span{font-size: 28px;width: 28px;line-height: 28px;}.uagb-block-84cb56a6 .uagb-iconbox-icon-wrap{width: 28px;height: 28px;line-height: 28px;}.uagb-block-84cb56a6 .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-84cb56a6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-84cb56a6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-267e3d1f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-267e3d1f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-267e3d1f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 60px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5f92c391{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5f92c391 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5f92c391{padding-top: 30px;padding-bottom: 30px;padding-left: 24px;padding-right: 24px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-139d59e0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-139d59e0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-139d59e0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7350a023{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7350a023 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7350a023{padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1914c6be{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1914c6be > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1914c6be{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f480abf5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f480abf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f480abf5{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;background-color: #108847;;align-items: stretch;flex-wrap: wrap;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8c1b05f8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8c1b05f8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-8c1b05f8 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8c1b05f8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-96d22959{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-96d22959 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-96d22959{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;border-style: solid;background-color: ;;flex-wrap: wrap;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b2d69344 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b2d69344 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b2d69344 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-b2d69344 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b2d69344.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d7e7012b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d7e7012b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d7e7012b{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;background-color: #108847;;flex-wrap: wrap;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-524bae82 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-524bae82 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-524bae82 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-524bae82 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-524bae82.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-524bae82.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52e24014{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52e24014 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-52e24014{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89a30c20{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89a30c20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-89a30c20{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;border-style: solid;background-color: ;;align-items: stretch;flex-wrap: wrap;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ce13dcb6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ce13dcb6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-ce13dcb6 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ce13dcb6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d98aca1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d98aca1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9d98aca1{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;background-color: #108847;;flex-wrap: wrap;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a676cdba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a676cdba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a676cdba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-a676cdba .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a676cdba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-372ea69a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-372ea69a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-372ea69a{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 15px !important;margin-bottom: 15px !important;margin-left: 15px;margin-right: 15px;order: initial;border-style: solid;background-color: ;;flex-wrap: wrap;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ba88ddd6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ba88ddd6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-image-content img{width: 65px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 65px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 65px;}.uagb-block-ba88ddd6 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 65px;}.uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ba88ddd6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c9f40731{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c9f40731 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c9f40731{padding-top: 0px;padding-bottom: 0px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-558d00ae{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-558d00ae > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-558d00ae{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8bd6b4e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8bd6b4e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e8bd6b4e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d15b022e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d15b022e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d15b022e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;flex-wrap: wrap;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-default figure img{border-style: solid;border-color: #108847;}.uagb-block-ecb3ccea.wp-block-uagb-image--layout-overlay figure img{border-style: solid;border-color: #108847;}.uagb-block-ecb3ccea.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 340px;height: 400px;}.uagb-block-ecb3ccea.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-ecb3ccea .wp-block-uagb-image__figure{align-items: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0b57ac7e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0b57ac7e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0b57ac7e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: center;flex-wrap: wrap;}.uagb-block-bc32a53b.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-bc32a53b .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-bc32a53b .spectra-image-gallery__control-button{padding:    ;}.uagb-block-bc32a53b .spectra-image-gallery__layout--grid{grid-gap: 10px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--isogrid{margin: -5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--masonry{margin: -5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 5px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 10px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -10px;}.uagb-block-bc32a53b .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 10px;}.uagb-block-bc32a53b .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-bc32a53b+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-80d49ee2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-80d49ee2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-80d49ee2{padding-top: 64px;padding-bottom: 64px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;}.wp-block-uagb-advanced-heading.uagb-block-5d3eb422.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 14px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e93f1702{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e93f1702 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 50px;}.wp-block-uagb-container.uagb-block-e93f1702{padding-top: 24px;padding-bottom: 64px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 50px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4669201{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4669201 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b4669201{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b4669201.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-b4669201.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e87369d3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e87369d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e87369d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e87369d3.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-e87369d3.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-865bd391.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 203px;height: auto;}.uagb-block-865bd391.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-865bd391 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-32c44910{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-32c44910 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-32c44910{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 12px;height: 12px;line-height: 12px;font-size: 12px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 12px;font-size: 12px;}.uagb-block-fb798284 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-fb798284 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fb798284 .uagb-ifb-icon{width: 12px;line-height: 12px;}.uagb-block-fb798284 .uagb-ifb-icon > span{font-size: 12px;width: 12px;line-height: 12px;}.uagb-block-fb798284 .uagb-iconbox-icon-wrap{width: 12px;height: 12px;line-height: 12px;}.uagb-block-fb798284.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-fb798284.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6125e5f1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6125e5f1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6125e5f1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6125e5f1.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-6125e5f1.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3fc5dc73{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3fc5dc73 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3fc5dc73{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3fc5dc73.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-3fc5dc73.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-ea7d81d8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 203px;height: auto;}.uagb-block-ea7d81d8.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-ea7d81d8 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-15dc585c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-15dc585c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-15dc585c{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 12px;height: 12px;line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 12px;line-height: 12px;font-size: 12px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-36cf55f5 .uagb-ifb-icon{width: 12px;line-height: 12px;}.uagb-block-36cf55f5 .uagb-ifb-icon > span{font-size: 12px;width: 12px;line-height: 12px;}.uagb-block-36cf55f5 .uagb-iconbox-icon-wrap{width: 12px;height: 12px;line-height: 12px;}.uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-36cf55f5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f353843{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f353843 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9f353843{padding-top: 50px;padding-bottom: 50px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 30px;column-gap: 0px;order: initial;background-image: url(https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Scenario-2.webp);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-9f353843::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #108847;opacity: 0.86;}.uagb-block-56fcfc1a.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-56fcfc1a.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-56fcfc1a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-56fcfc1a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-56fcfc1a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 10px;}[dir=rtl] .uagb-block-56fcfc1a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 10px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6ff30b2d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6ff30b2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6ff30b2d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 20px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-4);;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-739ccf6c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.uagb-block-fbc62094.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-fbc62094 .uagb-slider.round{border-radius: 20px !important;}.uagb-block-fbc62094 .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #dddddd;}.uagb-block-fbc62094 .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-fbc62094 .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-fbc62094 .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all 0.2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}\n.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}\n.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\";s:2:\"js\";s:1009:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-93af6ed7' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-fd369e15' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-2b3de640' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-a4ce54b0' );\n});\nwindow.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"fbc62094\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSecretKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"reCaptchaSecretKeyV3\":\"\",\"afterSubmitToEmail\":\"\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Envio de formulu00e1rio\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Preencha o captcha acima.\",\"confirmationUrl\":\"\"}, '.uagb-block-fbc62094', 7 );\n});\n });\";s:18:\"current_block_list\";a:28:{i:0;s:14:\"uagb\/container\";i:3;s:10:\"core\/image\";i:6;s:21:\"uagb\/advanced-heading\";i:8;s:10:\"uagb\/image\";i:9;s:13:\"uagb\/info-box\";i:10;s:14:\"core\/paragraph\";i:13;s:12:\"uagb\/buttons\";i:14;s:18:\"uagb\/buttons-child\";i:16;s:14:\"core\/shortcode\";i:17;s:11:\"core\/spacer\";i:20;s:10:\"core\/group\";i:22;s:18:\"uagb\/image-gallery\";i:23;s:10:\"uagb\/forms\";i:24;s:15:\"uagb\/forms-name\";i:25;s:16:\"uagb\/forms-email\";i:26;s:19:\"uagb\/forms-textarea\";i:27;s:23:\"surecart\/slide-out-cart\";i:28;s:30:\"surecart\/slide-out-cart-header\";i:29;s:29:\"surecart\/slide-out-cart-items\";i:30;s:30:\"surecart\/slide-out-cart-coupon\";i:31;s:32:\"surecart\/slide-out-cart-subtotal\";i:32;s:38:\"surecart\/slide-out-cart-bump-line-item\";i:33;s:30:\"surecart\/slide-out-cart-submit\";i:34;s:11:\"core\/search\";i:36;s:12:\"core\/heading\";i:37;s:15:\"core\/categories\";i:38;s:14:\"uagb\/icon-list\";i:39;s:20:\"uagb\/icon-list-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778470349\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"wpil_sync_report3":["1"],"rank_math_internal_links_processed":["1"],"_uag_css_file_name":["uag-css-7.css"],"_uag_js_file_name":["uag-js-7.js"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"info@joobond.com","author_link":"https:\/\/joobond.com\/es\/author\/infojoobond-com\/"},"uagb_comment_info":0,"uagb_excerpt":"We Help Your Business Build Stronger Bonds. Our advanced adhesive solutions help industries achieve durable, high-performance results in automotive, construction and manufacturing. Let us strengthen your products. About We are a certified, high-performance adhesive manufacturer. Joobond is a specialized sealant producer committed to delivering superior bonding solutions for your industry. WHY CHOOSE US Smart Integration&hellip;","_links":{"self":[{"href":"https:\/\/joobond.com\/es\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joobond.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joobond.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joobond.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joobond.com\/es\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":0,"href":"https:\/\/joobond.com\/es\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"wp:attachment":[{"href":"https:\/\/joobond.com\/es\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}