{"id":2662,"date":"2025-06-05T17:00:05","date_gmt":"2025-06-05T09:00:05","guid":{"rendered":"https:\/\/joobond.com\/?post_type=product&#038;p=2662"},"modified":"2025-07-25T14:02:25","modified_gmt":"2025-07-25T06:02:25","slug":"j-518l-perekat-kaca-depan-otomotif-poliuretana","status":"publish","type":"product","link":"https:\/\/joobond.com\/id\/product\/j-518l-perekat-kaca-depan-otomotif-poliuretana\/","title":{"rendered":"Perekat Kaca Depan Otomotif Poliuretan J-518L"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-056b19b3 alignwide uagb-is-root-container\">\r\n<p class=\"has-ast-global-color-2-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">J-518L is one component moisture curing polyurethane automotive windshield adhesive. It has excellent bonding and sealing performance, and it is simple operation, good anti-sagging, fast curing,modest hardness after curing, excellent water and aging resistant, etc.<\/p>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-uagb-container uagb-block-4942767d alignwide uagb-is-root-container\">\r\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a896c3fc\">\r\n<h2 class=\"uagb-heading-text\">Product Features<\/h2>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-uagb-container uagb-block-d5218cd4 alignwide uagb-is-root-container\">\r\n<ul class=\"wp-block-list has-black-color has-text-color has-link-color wp-elements-2\">\r\n<li class=\"has-ast-global-color-0-color has-text-color has-link-color wp-elements-3\">Solvent-free<\/li>\r\n\r\n\r\n\r\n<li>High strength, fast curing,medium viscosity.<\/li>\r\n\r\n\r\n\r\n<li>Excellent adhesion, no primer required.<\/li>\r\n<\/ul>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-uagb-container uagb-block-1a8fc4cb alignwide uagb-is-root-container\">\r\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ad9c2a18\">\r\n<h2 class=\"uagb-heading-text\">Areas of Application<\/h2>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-uagb-container uagb-block-72de460a alignwide uagb-is-root-container\">\r\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">Suitable for windshield and side &amp; back window glass bonding<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<figure data-spectra-id=\"spectra-cec2b774-f700-4f5a-813e-55ddf5b606bf\" class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-id=\"2551\" class=\"wp-image-2551\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/1.webp\" alt=\"\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/1.webp 1000w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/1-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/1-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/1-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/1-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/1-100x100.webp 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure data-spectra-id=\"spectra-68a55efa-94ee-469f-811b-4d8b404545a7\" class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-id=\"2552\" class=\"wp-image-2552\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/2.webp\" alt=\"\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/2.webp 1000w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/2-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/2-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/2-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/2-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/2-100x100.webp 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure data-spectra-id=\"spectra-084fd325-aa37-4b5c-8a58-056c56ba9703\" class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-id=\"2553\" class=\"wp-image-2553\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/3.webp\" alt=\"\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/3.webp 1000w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/3-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/3-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/3-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/3-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/3-100x100.webp 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\r\n\r\n\r\n\r\n<figure data-spectra-id=\"spectra-db38c2b5-1620-41ae-8092-09a0f911226a\" class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" data-id=\"2550\" class=\"wp-image-2550\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/4.webp\" alt=\"\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/4.webp 1000w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/4-300x300.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/4-150x150.webp 150w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/4-768x768.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/4-600x600.webp 600w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/4-100x100.webp 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-uagb-container uagb-block-938f20fc alignwide uagb-is-root-container\">\r\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7e43a969\">\r\n<h2 class=\"uagb-heading-text\">Packing Specification<\/h2>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-uagb-container uagb-block-d5eb0660 alignwide uagb-is-root-container\">\r\n<ul class=\"wp-block-list\">\r\n<li class=\"has-black-color has-text-color has-link-color wp-elements-5\">Cartridge: 310ml; 12pcs\/20pcs\/24pcs per carton<\/li>\r\n\r\n\r\n\r\n<li class=\"has-black-color has-text-color has-link-color wp-elements-6\">Sausage: 400ml\/600ml; 20pcs per carton<\/li>\r\n\r\n\r\n\r\n<li class=\"has-black-color has-text-color has-link-color wp-elements-7\">Barrel: 200L\/250KGS<\/li>\r\n<\/ul>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-uagb-container uagb-block-d2654924 alignwide uagb-is-root-container\">\r\n<figure data-spectra-id=\"spectra-42ebf8a3-262e-46af-9b1b-404e0f81b207\" class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"452\" class=\"wp-image-2342\" src=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Product-bottom.webp\" alt=\"\" srcset=\"https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Product-bottom.webp 1000w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Product-bottom-300x136.webp 300w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Product-bottom-768x347.webp 768w, https:\/\/joobond.com\/wp-content\/uploads\/2025\/05\/Product-bottom-600x271.webp 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Place of Origin: China<br \/>Brand Name: OEM<br \/>Certification: GB\/T 13477.2, GB\/T 13477.4, GB\/T 13477.5, GB\/T 13477.6, HG\/T 4363, GB\/T 2793, GB\/T 531.1, GB\/T 528, GB\/T 7124<br \/>Model Number: J-518L<br \/>Packaging Details: 400ml, 600ml<br \/>Delivery Time: 20-30days<br \/>Payment Terms: T\/T, L\/C<\/p>","protected":false},"featured_media":2671,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"spectra_gs_classes":""},"product_brand":[],"product_cat":[53,62],"product_tag":[76],"class_list":["post-2662","product","type-product","status-publish","has-post-thumbnail","product_cat-polyurethane-sealant","product_cat-windshield-adhesive","product_tag-automotive-sealant","desktop-align-center","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","shipping-taxable","product-type-simple"],"acf":[],"spectra_custom_meta":{"total_sales":["0"],"_tax_status":["taxable"],"_tax_class":[""],"_manage_stock":["no"],"_backorders":["no"],"_sold_individually":["no"],"_virtual":["no"],"_downloadable":["no"],"_download_limit":["-1"],"_download_expiry":["-1"],"_thumbnail_id":["2671"],"_stock":[null],"_stock_status":["instock"],"_wc_average_rating":["0"],"_wc_review_count":["0"],"_product_version":["10.0.3"],"rank_math_seo_score":["16"],"rank_math_contentai_score":["a:5:{s:8:\"keywords\";s:5:\"74.51\";s:9:\"wordCount\";s:1:\"0\";s:9:\"linkCount\";s:1:\"0\";s:12:\"headingCount\";s:1:\"0\";s:10:\"mediaCount\";s:1:\"0\";}"],"product_specs_0_spec_name":["<strong>Testing Items<\/strong>"],"_product_specs_0_spec_name":["field_680f48f09c315"],"product_specs_0_spec_value":["<strong>Typical Value<\/strong>"],"_product_specs_0_spec_value":["field_680f48f89c316"],"product_specs_1_spec_name":["Appearance"],"_product_specs_1_spec_name":["field_680f48f09c315"],"product_specs_1_spec_value":["Black homogenous paste"],"_product_specs_1_spec_value":["field_680f48f89c316"],"product_specs_2_spec_name":["Density (g\/cm\u00b3)"],"_product_specs_2_spec_name":["field_680f48f09c315"],"product_specs_2_spec_value":["1.50"],"_product_specs_2_spec_value":["field_680f48f89c316"],"product_specs_3_spec_name":["Sagging properties (mm)"],"_product_specs_3_spec_name":["field_680f48f09c315"],"product_specs_3_spec_value":["0"],"_product_specs_3_spec_value":["field_680f48f89c316"],"product_specs_4_spec_name":["Tack free time (min)"],"_product_specs_4_spec_name":["field_680f48f09c315"],"product_specs_4_spec_value":["30"],"_product_specs_4_spec_value":["field_680f48f89c316"],"product_specs_5_spec_name":["Curing speed (mm\/d)"],"_product_specs_5_spec_name":["field_680f48f09c315"],"product_specs_5_spec_value":["3.5"],"_product_specs_5_spec_value":["field_680f48f89c316"],"product_specs_6_spec_name":["Volatile content (%)"],"_product_specs_6_spec_name":["field_680f48f09c315"],"product_specs_6_spec_value":["3"],"_product_specs_6_spec_value":["field_680f48f89c316"],"product_specs_7_spec_name":["ShoreA-hardness (A\u00b0)"],"_product_specs_7_spec_name":["field_680f48f09c315"],"product_specs_7_spec_value":["65"],"_product_specs_7_spec_value":["field_680f48f89c316"],"product_specs_8_spec_name":["Tensile strength (Mpa)"],"_product_specs_8_spec_name":["field_680f48f09c315"],"product_specs_8_spec_value":["3.5"],"_product_specs_8_spec_value":["field_680f48f89c316"],"product_specs_9_spec_name":["Elongation at break (%)"],"_product_specs_9_spec_name":["field_680f48f09c315"],"product_specs_9_spec_value":["320"],"_product_specs_9_spec_value":["field_680f48f89c316"],"product_specs":["12"],"_product_specs":["field_680f46408ab8c"],"_monsterinsights_skip_tracking":["0"],"_monsterinsights_sitenote_active":["0"],"rank_math_primary_product_brand":["0"],"rank_math_primary_product_cat":["53"],"site-sidebar-layout":["default"],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"theme-transparent-header-meta":["default"],"product_specs_0_spec_value_copy":["Standard"],"_product_specs_0_spec_value_copy":["field_682add276e57f"],"product_specs_1_spec_value_copy":["\/"],"_product_specs_1_spec_value_copy":["field_682add276e57f"],"product_specs_2_spec_value_copy":["1.5\u00b10.1"],"_product_specs_2_spec_value_copy":["field_682add276e57f"],"product_specs_3_spec_value_copy":["\u22640"],"_product_specs_3_spec_value_copy":["field_682add276e57f"],"product_specs_4_spec_value_copy":["30-40"],"_product_specs_4_spec_value_copy":["field_682add276e57f"],"product_specs_5_spec_value_copy":["\u22653.0"],"_product_specs_5_spec_value_copy":["field_682add276e57f"],"product_specs_6_spec_value_copy":["\u22645"],"_product_specs_6_spec_value_copy":["field_682add276e57f"],"product_specs_7_spec_value_copy":["60.-70"],"_product_specs_7_spec_value_copy":["field_682add276e57f"],"product_specs_8_spec_value_copy":["\u22653"],"_product_specs_8_spec_value_copy":["field_682add276e57f"],"product_specs_9_spec_value_copy":["\u2265300"],"_product_specs_9_spec_value_copy":["field_682add276e57f"],"product_specs_10_spec_name":["Tensile- shear strength (Mpa)"],"_product_specs_10_spec_name":["field_680f48f09c315"],"product_specs_10_spec_value_copy":["\u22652"],"_product_specs_10_spec_value_copy":["field_682add276e57f"],"product_specs_10_spec_value":["2.5"],"_product_specs_10_spec_value":["field_680f48f89c316"],"product_specs_11_spec_name":["Extrudability (ml\/ min)"],"_product_specs_11_spec_name":["field_680f48f09c315"],"product_specs_11_spec_value_copy":["\u226560"],"_product_specs_11_spec_value_copy":["field_682add276e57f"],"product_specs_11_spec_value":["110"],"_product_specs_11_spec_value":["field_680f48f89c316"],"_edit_lock":["1753423213:2"],"wp_statistics_words_count":["65"],"_uag_custom_page_level_css":[""],"site-content-layout":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"_edit_last":["2"],"astra-migrate-meta-layouts":["set"],"_uag_page_assets":["a:9:{s:3:\"css\";s:31418:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:0.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}\n.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all 0.3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}\n.wp-block-uagb-container.uagb-block-056b19b3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-056b19b3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-056b19b3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-056b19b3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-056b19b3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-056b19b3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-056b19b3{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4942767d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4942767d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4942767d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4942767d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4942767d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4942767d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-4942767d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #a9ba20;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a896c3fc.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-a896c3fc.wp-block-uagb-advanced-heading {padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-a896c3fc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a896c3fc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a896c3fc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a896c3fc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a896c3fc .uagb-heading-text{font-size: 18px;line-height: 2em;}.wp-block-uagb-container.uagb-block-d5218cd4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5218cd4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5218cd4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5218cd4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5218cd4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5218cd4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d5218cd4{box-shadow: 0px 0px   #00000070 ;padding-top: 5px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1a8fc4cb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1a8fc4cb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1a8fc4cb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1a8fc4cb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1a8fc4cb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a8fc4cb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-1a8fc4cb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #a9ba20;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ad9c2a18.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-ad9c2a18.wp-block-uagb-advanced-heading {padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-ad9c2a18.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ad9c2a18.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ad9c2a18.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ad9c2a18.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ad9c2a18 .uagb-heading-text{font-size: 18px;line-height: 2em;}.wp-block-uagb-container.uagb-block-72de460a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-72de460a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-72de460a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-72de460a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-72de460a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72de460a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-72de460a{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-938f20fc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-938f20fc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-938f20fc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-938f20fc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-938f20fc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-938f20fc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-938f20fc{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #a9ba20;;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-7e43a969.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-7e43a969.wp-block-uagb-advanced-heading {padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-7e43a969.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7e43a969.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e43a969.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e43a969.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e43a969 .uagb-heading-text{font-size: 18px;line-height: 2em;}.wp-block-uagb-container.uagb-block-d5eb0660 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5eb0660 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5eb0660 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d5eb0660 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d5eb0660 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5eb0660{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d5eb0660{box-shadow: 0px 0px   #00000070 ;padding-top: 5px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d2654924 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d2654924 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d2654924 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d2654924 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d2654924 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d2654924{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d2654924{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-056b19b3{width: 100%;}.wp-block-uagb-container.uagb-block-056b19b3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4942767d{width: 100%;}.wp-block-uagb-container.uagb-block-4942767d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #a9ba20;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5218cd4{width: 100%;}.wp-block-uagb-container.uagb-block-d5218cd4{padding-top: 5px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a8fc4cb{width: 100%;}.wp-block-uagb-container.uagb-block-1a8fc4cb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #a9ba20;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72de460a{width: 100%;}.wp-block-uagb-container.uagb-block-72de460a{padding-top: 20px;padding-bottom: 20px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-938f20fc{width: 100%;}.wp-block-uagb-container.uagb-block-938f20fc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #a9ba20;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5eb0660{width: 100%;}.wp-block-uagb-container.uagb-block-d5eb0660{padding-top: 5px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d2654924{width: 100%;}.wp-block-uagb-container.uagb-block-d2654924{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-056b19b3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-056b19b3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4942767d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-4942767d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #a9ba20;;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5218cd4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d5218cd4{padding-top: 5px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1a8fc4cb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-1a8fc4cb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #a9ba20;;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72de460a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-72de460a{padding-top: 20px;padding-bottom: 20px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-938f20fc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-938f20fc{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #a9ba20;;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d5eb0660{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d5eb0660{padding-top: 5px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d2654924{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d2654924{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all 0.2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}\n.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}\n.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child{text-decoration: !important;font-weight: 600;line-height: em;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-75fa870d.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-5bf81fd2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__label{text-align: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-b5768981 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-b5768981 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-icon-list.uagb-block-b5768981.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:20:{i:0;s:14:\"uagb\/container\";i:1;s:14:\"core\/paragraph\";i:3;s:21:\"uagb\/advanced-heading\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:12:\"core\/gallery\";i:8;s:10:\"core\/image\";i:9;s:23:\"surecart\/slide-out-cart\";i:10;s:30:\"surecart\/slide-out-cart-header\";i:11;s:29:\"surecart\/slide-out-cart-items\";i:12;s:30:\"surecart\/slide-out-cart-coupon\";i:13;s:32:\"surecart\/slide-out-cart-subtotal\";i:14;s:38:\"surecart\/slide-out-cart-bump-line-item\";i:15;s:30:\"surecart\/slide-out-cart-submit\";i:16;s:11:\"core\/search\";i:17;s:10:\"core\/group\";i:18;s:12:\"core\/heading\";i:19;s:15:\"core\/categories\";i:20;s:14:\"uagb\/icon-list\";i:21;s:20:\"uagb\/icon-list-child\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788163401\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"rank_math_internal_links_processed":["1"],"_uag_css_file_name":["uag-css-2662.css"]},"uagb_featured_image_src":{"full":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L.webp",800,800,false],"thumbnail":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-150x150.webp",150,150,true],"medium":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-300x300.webp",300,300,true],"medium_large":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-768x768.webp",768,768,true],"large":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L.webp",800,800,false],"1536x1536":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L.webp",800,800,false],"2048x2048":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L.webp",800,800,false],"trp-custom-language-flag":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L.webp",12,12,false],"woocommerce_thumbnail":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-600x600.webp",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/joobond.com\/wp-content\/uploads\/2025\/06\/J-518L-100x100.webp",100,100,true]},"uagb_author_info":{"display_name":"xiaoxi99201","author_link":"https:\/\/joobond.com\/id\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Place of Origin: ChinaBrand Name: OEMCertification: GB\/T 13477.2, GB\/T 13477.4, GB\/T 13477.5, GB\/T 13477.6, HG\/T 4363, GB\/T 2793, GB\/T 531.1, GB\/T 528, GB\/T 7124Model Number: J-518LPackaging Details: 400ml, 600mlDelivery Time: 20-30daysPayment Terms: T\/T, L\/C","_links":{"self":[{"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/product\/2662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/media\/2671"}],"wp:attachment":[{"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/media?parent=2662"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/product_brand?post=2662"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/product_cat?post=2662"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/joobond.com\/id\/wp-json\/wp\/v2\/product_tag?post=2662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}